{"id":128194,"date":"2025-05-28T14:27:52","date_gmt":"2025-05-28T17:27:52","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=128194"},"modified":"2025-05-28T14:28:14","modified_gmt":"2025-05-28T17:28:14","slug":"leticia-atique-branco-lanca-livro-sobre-politicas-publicas-para-a-juventude-em-jundiai","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2025\/05\/28\/leticia-atique-branco-lanca-livro-sobre-politicas-publicas-para-a-juventude-em-jundiai\/","title":{"rendered":"Let\u00edcia Atique Branco lan\u00e7a livro sobre pol\u00edticas p\u00fablicas para a juventude em Jundia\u00ed"},"content":{"rendered":"\n<p>Na pr\u00f3xima quinta-feira, 29 de maio, \u00e0s 19h, ser\u00e1 realizado o evento de lan\u00e7amento do livro <em>\u201cPlanejamento e Execu\u00e7\u00e3o de Pol\u00edticas P\u00fablicas para a Juventude\u201d,<\/em> da autora Let\u00edcia Atique Branco. O encontro acontece no HUB de Inova\u00e7\u00e3o do Campus da UniAnchieta, em Jundia\u00ed, e contar\u00e1 com venda de exemplares no local.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815-960x960.png\" alt=\"\" class=\"wp-image-128208\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815-960x960.png 960w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815-300x300.png 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815-100x100.png 100w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815-768x768.png 768w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0815.png 1080w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>Publicada no dia 4 de maio pela Editora Appris, a obra j\u00e1 est\u00e1 dispon\u00edvel em plataformas como Amazon e Mercado Livre. O livro \u00e9 fruto da viv\u00eancia de Let\u00edcia como Assessora de Pol\u00edticas para a Juventude em Jundia\u00ed e nasce do desejo de apoiar gestores p\u00fablicos, conselhos de juventude, governos locais e sociedade civil na constru\u00e7\u00e3o de pol\u00edticas estruturantes e efetivas voltadas aos jovens.<\/p>\n\n\n\n<p>A ideia surgiu durante o 7\u00ba Conexidades, em S\u00e3o Sebasti\u00e3o, quando, incentivada por colegas das cidades de Campinas e Praia Grande, Let\u00edcia decidiu transformar suas experi\u00eancias em um material acess\u00edvel e \u00fatil para quem atua ou deseja atuar na \u00e1rea.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520-640x960.jpg\" alt=\"\" class=\"wp-image-128210\" style=\"aspect-ratio:1;object-fit:cover;width:429px;height:auto\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520-640x960.jpg 640w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520-300x450.jpg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520-768x1152.jpg 768w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520-1024x1536.jpg 1024w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2025\/05\/IMG_0520.jpg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>\u201cPensei nos jovens que recebem a oportunidade \u2014 e o desafio \u2014 de trabalhar com pol\u00edticas p\u00fablicas para a juventude, muitas vezes sem saber por onde come\u00e7ar\u201d, conta a autora. \u201cQuis escrever algo que fosse realmente pr\u00e1tico, baseado na realidade dos munic\u00edpios, e que ajudasse a construir um ecossistema de juventude forte e conectado \u00e0s necessidades dessa gera\u00e7\u00e3o.\u201d<\/strong><\/p>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Mais do que um guia, <em>\u201cPlanejamento e Execu\u00e7\u00e3o de Pol\u00edticas P\u00fablicas para a Juventude\u201d<\/em> \u00e9 descrito como um convite \u00e0 a\u00e7\u00e3o e \u00e0 transforma\u00e7\u00e3o da forma como as pol\u00edticas para essa faixa et\u00e1ria s\u00e3o pensadas e executadas no Brasil.<\/p>\n\n\n\n<p>A publica\u00e7\u00e3o conta com pref\u00e1cio assinado por Ramirez Lopes, ex-coordenador de Pol\u00edticas para a Juventude da Cidade de S\u00e3o Paulo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lan\u00e7amento do livro \u201cPlanejamento e Execu\u00e7\u00e3o de Pol\u00edticas P\u00fablicas para a Juventude&#8221;<\/strong><br><strong>Data:<\/strong> 29 de maio (quinta-feira)<br><strong>Hor\u00e1rio:<\/strong> 19h<br><strong>Local:<\/strong> HUB de Inova\u00e7\u00e3o do Campus Anchieta \u2013 Jundia\u00ed\/SP<br><strong>Entrada gratuita | Venda de exemplares no local<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Evento de lan\u00e7amento ocorre nesta quinta-feira (29), \u00e0s 19h, no Campus da UniAnchieta.<\/p>\n","protected":false},"author":24,"featured_media":128207,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2833],"tags":[],"class_list":["post-128194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/128194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=128194"}],"version-history":[{"count":2,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/128194\/revisions"}],"predecessor-version":[{"id":128212,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/128194\/revisions\/128212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/128207"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=128194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=128194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=128194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}