{"id":134107,"date":"2026-02-03T16:06:39","date_gmt":"2026-02-03T19:06:39","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=134107"},"modified":"2026-02-03T16:06:39","modified_gmt":"2026-02-03T19:06:39","slug":"vacina-contra-a-dengue-no-sus-como-funciona-e-onde-se-vacinar-em-jundiai","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2026\/02\/03\/vacina-contra-a-dengue-no-sus-como-funciona-e-onde-se-vacinar-em-jundiai\/","title":{"rendered":"Vacina contra a dengue no SUS: como funciona e onde se vacinar em Jundia\u00ed"},"content":{"rendered":"\n<p>A vacina\u00e7\u00e3o \u00e9 uma das principais a\u00e7\u00f5es de sa\u00fade p\u00fablica para prevenir doen\u00e7as e proteger a popula\u00e7\u00e3o. Em dezembro de 2023, o Minist\u00e9rio da Sa\u00fade incluiu a vacina contra a dengue no Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o. Como a oferta de doses \u00e9 limitada e depende do cronograma de entrega do fabricante, a implanta\u00e7\u00e3o ocorreu de forma gradual em todo o pa\u00eds. Em Jundia\u00ed, o imunizante passou a ser ofertado em julho de 2024.<\/p>\n\n\n\n<p>A vacina\u00e7\u00e3o contra a dengue, junto com outras medidas de preven\u00e7\u00e3o e controle da doen\u00e7a, contribui para reduzir casos, interna\u00e7\u00f5es e \u00f3bitos.<\/p>\n\n\n\n<p>Confira abaixo as principais d\u00favidas:<\/p>\n\n\n\n<p><strong>Quem pode se vacinar pelo SUS?<\/strong><br>Atualmente, a vacina contra a dengue no Sistema \u00danico de Sa\u00fade (SUS) \u00e9 recomendada para adolescentes de 10 a 14 anos, 11 meses e 29 dias.<br><br>Para que a estrat\u00e9gia seja efetiva e justa para todos, \u00e9 importante manter a vacina\u00e7\u00e3o exclusiva nessa faixa et\u00e1ria, salvo orienta\u00e7\u00f5es espec\u00edficas e tempor\u00e1rias do Minist\u00e9rio da Sa\u00fade (por exemplo, em situa\u00e7\u00f5es pontuais de remanejamento de doses por vencimento, quando aplic\u00e1vel).<\/p>\n\n\n\n<p><strong>Por qu\u00ea essa faixa et\u00e1ria \u00e9 priorit\u00e1ria?<\/strong><br>No SUS, essa faixa et\u00e1ria inicial de vacina\u00e7\u00e3o contra a dengue segue orienta\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade. Isso foi estabelecido porque esse p\u00fablico apresenta alta taxa de hospitaliza\u00e7\u00e3o por dengue, o que demanda uma estrat\u00e9gia de reduzir casos graves e interna\u00e7\u00e3o, e porque a vacina dispon\u00edvel (Qdenga) ainda tem quantidade limitada. Jundia\u00ed segue a diretriz nacional vigente e far\u00e1 a amplia\u00e7\u00e3o conforme novas remessas de vacina e orienta\u00e7\u00f5es atualizadas do Minist\u00e9rio da Sa\u00fade.<\/p>\n\n\n\n<p><strong>Qual o esquema vacinal?<\/strong><br>O esquema atual da vacina utilizada no SUS \u00e9 de duas doses, com um intervalo m\u00ednimo de cerca de 3 meses entre elas. At\u00e9 agora, n\u00e3o h\u00e1 indica\u00e7\u00e3o oficial de dose de refor\u00e7o ap\u00f3s as duas doses recomendadas, mas estudos continuam acompanhando por quanto tempo a prote\u00e7\u00e3o se mant\u00e9m.<\/p>\n\n\n\n<p><strong>Onde se vacinar em Jundia\u00ed?<\/strong><br>A vacina\u00e7\u00e3o contra a dengue est\u00e1 dispon\u00edvel:<\/p>\n\n\n\n<p>1) Em todas as Unidades B\u00e1sicas de Sa\u00fade (UBSs) e demais unidades de Aten\u00e7\u00e3o Prim\u00e1ria do munic\u00edpio, mediante o hor\u00e1rio de funcionamento de cada unidade.&nbsp;<a href=\"https:\/\/jundiai.sp.gov.br\/saude\/rede-de-atendimento\/rede-completa-de-atendimento\/\"><strong>Confira aqui a lista completa de equipamentos da rede.<\/strong><\/a><\/p>\n\n\n\n<p>2) No Parque da Uva, durante a 41\u00aa Festa da Uva e 12\u00aa Expo Vinhos de Jundia\u00ed (amplia\u00e7\u00e3o de acesso ao p\u00fablico-alvo)<br>\u2022 Sextas-feiras: 18h \u00e0s 21h<br>\u2022 S\u00e1bados e domingos: 11h \u00e0s 17h<\/p>\n\n\n\n<p><strong>O que preciso levar para me vacinar?<\/strong><br>Carteirinha de vacina\u00e7\u00e3o e documento de identifica\u00e7\u00e3o com foto.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fonte \/ Imagem: Prefeitura de Jundia\u00ed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vacina\u00e7\u00e3o contra a dengue, junto com outras medidas de preven\u00e7\u00e3o e controle da doen\u00e7a, contribui para reduzir casos, interna\u00e7\u00f5es e \u00f3bitos<\/p>\n","protected":false},"author":24,"featured_media":134108,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,2839],"tags":[],"class_list":["post-134107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-saude"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/134107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=134107"}],"version-history":[{"count":1,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/134107\/revisions"}],"predecessor-version":[{"id":134109,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/134107\/revisions\/134109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/134108"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=134107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=134107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=134107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}