{"id":136529,"date":"2026-05-12T12:16:07","date_gmt":"2026-05-12T15:16:07","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=136529"},"modified":"2026-05-12T12:16:07","modified_gmt":"2026-05-12T15:16:07","slug":"prefeitura-segue-com-cronograma-preventivo-de-limpeza-e-drenagem-urbana","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2026\/05\/12\/prefeitura-segue-com-cronograma-preventivo-de-limpeza-e-drenagem-urbana\/","title":{"rendered":"Prefeitura segue com cronograma preventivo de limpeza e drenagem urbana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/05\/desassoreamento_pq_corrupira-3-1280x854-1-1200x801.jpg\" alt=\"\" class=\"wp-image-136530\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/05\/desassoreamento_pq_corrupira-3-1280x854-1-1200x801.jpg 1200w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/05\/desassoreamento_pq_corrupira-3-1280x854-1-300x200.jpg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/05\/desassoreamento_pq_corrupira-3-1280x854-1-768x512.jpg 768w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/05\/desassoreamento_pq_corrupira-3-1280x854-1.jpg 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Recentemente, as equipes atuaram na avenida Maria Negrini Negro, na regi\u00e3o do Caxambu, e na avenida S\u00e3o Jos\u00e9 da Pedra Santa, no Corrupira. Os trabalhos s\u00e3o coordenados pela Secretaria de Infraestrutura e Servi\u00e7os P\u00fablicos (SMISP) e seguem planejamento t\u00e9cnico elaborado pela unidade, al\u00e9m das demandas registradas pela popula\u00e7\u00e3o por meio do servi\u00e7o 156.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Os trabalhos de desassoreamento s\u00e3o executados em \u00e1reas urbanas e rurais. Paralelamente, as equipes realizam a limpeza de bocas de lobo e o hidrojateamento das galerias pluviais que desembocam diretamente nos c\u00f3rregos e rios da cidade. Os servi\u00e7os seguem um cronograma de manuten\u00e7\u00e3o preventiva em diversas regi\u00f5es, especialmente em locais com hist\u00f3rico de alagamentos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fonte\/Imagem Prefeitura de Jundia\u00ed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com foco na preven\u00e7\u00e3o e na melhoria do escoamento das \u00e1guas pluviais, a Prefeitura de Jundia\u00ed mant\u00e9m um cronograma cont\u00ednuo de limpeza e manuten\u00e7\u00e3o do sistema de drenagem em diferentes regi\u00f5es da cidade<\/p>\n","protected":false},"author":24,"featured_media":136531,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8391,8356,1],"tags":[],"class_list":["post-136529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infraestrutura","category-jundiai","category-noticias"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/136529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=136529"}],"version-history":[{"count":1,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/136529\/revisions"}],"predecessor-version":[{"id":136532,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/136529\/revisions\/136532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/136531"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=136529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=136529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=136529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}