{"id":138291,"date":"2026-07-15T14:46:47","date_gmt":"2026-07-15T17:46:47","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=138291"},"modified":"2026-07-15T14:46:57","modified_gmt":"2026-07-15T17:46:57","slug":"educacao-politica-passa-a-integrar-curriculo-escolar-brasileiro","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2026\/07\/15\/educacao-politica-passa-a-integrar-curriculo-escolar-brasileiro\/","title":{"rendered":"Educa\u00e7\u00e3o pol\u00edtica passa a integrar curr\u00edculo escolar brasileiro"},"content":{"rendered":"\n<p><em>Nova legisla\u00e7\u00e3o torna obrigat\u00f3ria a abordagem de educa\u00e7\u00e3o pol\u00edtica e direitos da cidadania nas escolas e cria a Semana Nacional da \u00c9tica e da Cidadania<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/07\/Educacao-no-curriculo-escolar-1200x800.png\" alt=\"\" class=\"wp-image-138292\" style=\"width:580px;height:auto\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/07\/Educacao-no-curriculo-escolar-1200x800.png 1200w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/07\/Educacao-no-curriculo-escolar-300x200.png 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/07\/Educacao-no-curriculo-escolar-768x512.png 768w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/07\/Educacao-no-curriculo-escolar.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>A educa\u00e7\u00e3o pol\u00edtica e os direitos da cidadania passam a fazer parte do curr\u00edculo obrigat\u00f3rio da educa\u00e7\u00e3o b\u00e1sica brasileira. A medida foi oficializada com a san\u00e7\u00e3o da Lei n\u00ba 15.468\/2026, publicada na \u00faltima ter\u00e7a-feira (14), e tem como objetivo ampliar a forma\u00e7\u00e3o cidad\u00e3 dos estudantes desde os primeiros anos da vida escolar.<\/p>\n\n\n\n<p>A nova legisla\u00e7\u00e3o altera a Lei de Diretrizes e Bases da Educa\u00e7\u00e3o Nacional (LDB) e determina que os conte\u00fados relacionados \u00e0 realidade social e pol\u00edtica do Brasil sejam abordados nas escolas. A proposta \u00e9 fortalecer o conhecimento sobre a organiza\u00e7\u00e3o da sociedade, o funcionamento das institui\u00e7\u00f5es, os direitos e deveres dos cidad\u00e3os e a participa\u00e7\u00e3o democr\u00e1tica.<\/p>\n\n\n\n<p>Com a mudan\u00e7a, as redes de ensino dever\u00e3o incluir esses temas nas atividades pedag\u00f3gicas, contribuindo para que os estudantes desenvolvam uma compreens\u00e3o mais ampla sobre cidadania e participa\u00e7\u00e3o na vida p\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Semana Nacional da \u00c9tica e da Cidadania<\/h2>\n\n\n\n<p>Al\u00e9m da inclus\u00e3o da educa\u00e7\u00e3o pol\u00edtica no curr\u00edculo escolar, foi sancionada a Lei n\u00ba 15.467\/2026, que cria a Semana Nacional da \u00c9tica e da Cidadania.<\/p>\n\n\n\n<p>A iniciativa ser\u00e1 realizada anualmente na primeira semana de maio em todo o territ\u00f3rio nacional. Durante o per\u00edodo, \u00f3rg\u00e3os p\u00fablicos, institui\u00e7\u00f5es de ensino, entidades representativas e organiza\u00e7\u00f5es da sociedade civil poder\u00e3o promover a\u00e7\u00f5es voltadas ao fortalecimento dos valores \u00e9ticos, ao exerc\u00edcio da cidadania e \u00e0 conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da participa\u00e7\u00e3o social e do combate \u00e0 corrup\u00e7\u00e3o.<\/p>\n\n\n\n<p>A expectativa \u00e9 que as novas medidas incentivem a forma\u00e7\u00e3o de cidad\u00e3os mais conscientes de seus direitos, deveres e do papel que desempenham na constru\u00e7\u00e3o da sociedade.<\/p>\n\n\n\n<p><em><strong>M\u00eddias TVTEC Jundia\u00ed<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova legisla\u00e7\u00e3o torna obrigat\u00f3ria a abordagem de educa\u00e7\u00e3o pol\u00edtica e direitos da cidadania nas escolas e cria a Semana Nacional da \u00c9tica e da Cidadania A educa\u00e7\u00e3o pol\u00edtica e os direitos da cidadania passam a fazer parte do curr\u00edculo obrigat\u00f3rio da educa\u00e7\u00e3o b\u00e1sica brasileira. A medida foi oficializada com a san\u00e7\u00e3o da Lei n\u00ba 15.468\/2026, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":138292,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,1],"tags":[],"class_list":["post-138291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-noticias"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/138291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=138291"}],"version-history":[{"count":1,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/138291\/revisions"}],"predecessor-version":[{"id":138293,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/138291\/revisions\/138293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/138292"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=138291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=138291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=138291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}