{"id":139569,"date":"2026-09-02T11:26:58","date_gmt":"2026-09-02T14:26:58","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=139569"},"modified":"2026-09-02T11:28:39","modified_gmt":"2026-09-02T14:28:39","slug":"feriadao-deve-levar-11-400-passageiros-a-rodoviaria-de-jundiai","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2026\/09\/02\/feriadao-deve-levar-11-400-passageiros-a-rodoviaria-de-jundiai\/","title":{"rendered":"Feriad\u00e3o deve levar 11.400 passageiros \u00e0 Rodovi\u00e1ria de Jundia\u00ed"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"707\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/09\/Captura-de-tela-2026-09-02-112235.png\" alt=\"\" class=\"wp-image-139570\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/09\/Captura-de-tela-2026-09-02-112235.png 1167w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/09\/Captura-de-tela-2026-09-02-112235-300x182.png 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2026\/09\/Captura-de-tela-2026-09-02-112235-768x465.png 768w\" sizes=\"auto, (max-width: 1167px) 100vw, 1167px\" \/><\/figure>\n\n\n\n<p>Mais de 11.400 passageiros s\u00e3o esperados na Rodovi\u00e1ria de Jundia\u00ed durante o feriad\u00e3o, com uma previs\u00e3o de mais de 445 \u00f4nibus no per\u00edodo. Diante do aumento na procura, a recomenda\u00e7\u00e3o \u00e9 que os passageiros antecipem a compra das passagens para evitar a falta de lugares.<\/p>\n\n\n\n<p>Entre os destinos mais procurados a partir do terminal est\u00e3o S\u00e3o Paulo, Campinas, Sorocaba, Serra Negra, Itu, Santos, S\u00e3o Vicente e Praia Grande. Quem pretende viajar para essas cidades deve se programar com anteced\u00eancia e garantir a passagem.<\/p>\n\n\n\n<p>As passagens adquiridas pela internet devem conter o selo de embarque, representado por um QR Code. Caso o documento n\u00e3o apresente o c\u00f3digo, o passageiro deve procurar a bilheteria da empresa respons\u00e1vel para realizar a retirada do selo antes do embarque.<\/p>\n\n\n\n<p>A recomenda\u00e7\u00e3o \u00e9 chegar \u00e0 rodovi\u00e1ria com pelo menos 30 minutos de anteced\u00eancia em rela\u00e7\u00e3o ao hor\u00e1rio de embarque. Os passageiros tamb\u00e9m devem adquirir as passagens apenas por fontes confi\u00e1veis e empresas que operam no terminal, evitando problemas no momento da viagem. Em caso de imprevistos, a remarca\u00e7\u00e3o ou o reembolso podem ser solicitados com at\u00e9 tr\u00eas horas de anteced\u00eancia, diretamente com a empresa de \u00f4nibus.<\/p>\n\n\n\n<p>Fonte: Jornal da Cidade \/ Foto: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 11.400 passageiros devem passar pela Rodovi\u00e1ria de Jundia\u00ed durante o feriad\u00e3o, com previs\u00e3o de 445 \u00f4nibus no per\u00edodo. Diante do aumento na demanda, a recomenda\u00e7\u00e3o \u00e9 antecipar a compra das passagens e chegar ao terminal com pelo menos 30 minutos de anteced\u00eancia.<\/p>\n","protected":false},"author":24,"featured_media":139577,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2834,29,8356,5697,3059,2825],"tags":[],"class_list":["post-139569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-destaque","category-jundiai","category-mobilidade-noticias","category-transportes","category-turismo"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/139569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=139569"}],"version-history":[{"count":3,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/139569\/revisions"}],"predecessor-version":[{"id":139580,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/139569\/revisions\/139580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/139577"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=139569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=139569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=139569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}