{"id":14143,"date":"2018-07-20T08:00:33","date_gmt":"2018-07-20T11:00:33","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=14143"},"modified":"2018-07-19T14:16:33","modified_gmt":"2018-07-19T17:16:33","slug":"final-de-semana-sera-quente-e-seco-em-jundiai","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2018\/07\/20\/final-de-semana-sera-quente-e-seco-em-jundiai\/","title":{"rendered":"Final de semana ser\u00e1 quente e seco em Jundia\u00ed"},"content":{"rendered":"<div id=\"attachment_14158\" style=\"width: 410px\" class=\"wp-caption alignright\"><a href=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/07\/WhatsApp-Image-2018-07-19-at-14.13.40-e1532020560685.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14158\" class=\"wp-image-14158\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/07\/WhatsApp-Image-2018-07-19-at-14.13.40-e1532020560685-300x207.jpeg\" alt=\"\" width=\"400\" height=\"276\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/07\/WhatsApp-Image-2018-07-19-at-14.13.40-e1532020560685-300x207.jpeg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/07\/WhatsApp-Image-2018-07-19-at-14.13.40-e1532020560685.jpeg 579w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-14158\" class=\"wp-caption-text\"><em>(Zeppelin Drones)<\/em><\/p><\/div>\n<p>O\u00a0estado de S\u00e3o Paulo tem sido um dos locais mais secos do Brasil nessa semana, com baixos n\u00edveis de umidade e\u00a0altas temperaturas: os term\u00f4metros est\u00e3o marcando mais de 30\u00b0C em muitas \u00e1reas do Estado. Pelo menos at\u00e9 esta sexta-feira (20), nada muda no clima do\u00a0Sudeste.\u00a0Toda a regi\u00e3o continua ensolarada, sem condi\u00e7\u00f5es para chuva e com temperatura elevada, em geral acima do normal para os padr\u00f5es de julho.<\/p>\n<p>Em\u00a0S\u00e3o Paulo, a nebulosidade e a umidade no ar aumentam durante o s\u00e1bado em parte do estado, mas s\u00f3 h\u00e1 previs\u00e3o de chuva para o litoral no domingo. Na Grande S\u00e3o Paulo, como em todo o leste do estado, o domingo, 22 de julho, ser\u00e1 \u00famido e com temperatura amena. Pode garoar em alguns locais do sul da Grande S\u00e3o Paulo.<\/p>\n<p>J\u00e1 em Jundia\u00ed, a sexta-feira segue ensolarado. O s\u00e1bado (21) tem c\u00e9u com muitas nuvens e temperaturas entre 15\u00baC e 26\u00baC. Nestes dias, a umidade relativa do ar permanece na casa d0 31% a 69%. No domingo (22), as temperaturas caem um pouco e ficam entre 14\u00baC e 22\u00baC, enquanto a umidade do ar aumenta para 50% a 94%<\/p>\n<p>De acordo com o Climatempo, a chuva deve chegar somente no fim do m\u00eas de julho, quando\u00a0uma forte frente fria pode aumentar a possibilidade\u00a0de chuva no Sudeste. A previs\u00e3o \u00e9 que esta frente fria provoque chuvas na regi\u00e3o entre os dias 25 e 28 de julho, mas n\u00e3o ser\u00e1 chuva generalizada. O ar frio desta frente fria causa queda da temperatura acentuada.<\/p>\n<p><em>(Fonte: Climatempo)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chuvas devem chegar ao Sudeste somente no fim de julho<\/p>\n","protected":false},"author":10,"featured_media":14158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2834,3185,29],"tags":[3190,3621,5,2921,15],"class_list":["post-14143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-clima","category-destaque","tag-climatempo","tag-inmet","tag-jundiai","tag-previsao-do-tempo","tag-tvtec"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/14143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=14143"}],"version-history":[{"count":2,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/14143\/revisions"}],"predecessor-version":[{"id":14159,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/14143\/revisions\/14159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/14158"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=14143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=14143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=14143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}