{"id":31373,"date":"2019-05-29T10:38:43","date_gmt":"2019-05-29T13:38:43","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=31373"},"modified":"2019-05-29T11:08:06","modified_gmt":"2019-05-29T14:08:06","slug":"ciee-oferece-243-vagas-de-estagio-em-jundiai1","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2019\/05\/29\/ciee-oferece-243-vagas-de-estagio-em-jundiai1\/","title":{"rendered":"CIEE oferece 243 vagas de est\u00e1gio em Jundia\u00ed"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O Centro de Integra\u00e7\u00e3o Empresa-Escola (CIEE) de Jundia\u00ed (SP) est\u00e1 com 243 vagas de est\u00e1gio abertas para os cursos de pedagogia, administra\u00e7\u00e3o, engenharias mec\u00e2nica e de produ\u00e7\u00e3o, tecnologia da informa\u00e7\u00e3o e tamb\u00e9m para estudantes do ensino m\u00e9dio.<\/p>\n<div id=\"attachment_31374\" style=\"width: 408px\" class=\"wp-caption alignright\"><a href=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-31374\" class=\"wp-image-31374\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada-300x169.jpg\" alt=\"\" width=\"398\" height=\"224\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada-300x169.jpg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada-768x432.jpg 768w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada-1200x675.jpg 1200w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2019\/05\/8-fachada.jpg 2048w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/><\/a><p id=\"caption-attachment-31374\" class=\"wp-caption-text\">Para concorrer os estudantes devem fazer o cadastro gratuito no\u00a0site da institui\u00e7\u00e3o.<\/p><\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"22\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Para concorrer os estudantes devem fazer o cadastro gratuito no\u00a0<a href=\"https:\/\/portal.ciee.org.br\/unidade\/unidade-jundiai\/\" target=\"_blank\" rel=\"noopener noreferrer\">site da institui\u00e7\u00e3o<\/a>. Podem estagiar estudantes com 16 anos ou mais.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"55\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Todos os candidatos devem apresentar RG e CPF, comprova\u00e7\u00e3o de matr\u00edcula e frequ\u00eancia nos cursos de ensino m\u00e9dio, educa\u00e7\u00e3o profissional, ensino superior ou educa\u00e7\u00e3o especial, e nos anos finais do ensino fundamental, se for em uma unidade de Educa\u00e7\u00e3o de Jovens e Adultos (EJA). A institui\u00e7\u00e3o de ensino tamb\u00e9m precisa atestar a frequ\u00eancia do aluno.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"2\" data-block-id=\"5\">\n<div class=\"content-intertitle\">\n<p><strong>Mais vagas<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A empresa Super Est\u00e1gios tamb\u00e9m est\u00e1 com 50 vagas abertas em Jundia\u00ed, na \u00e1rea de marketing, publicidade, administra\u00e7\u00e3o, engenharia eletr\u00f4nica, com\u00e9rcio exterior e gest\u00e3o de qualidade. Mais informa\u00e7\u00f5es sobre as vagas podem ser obtidas no\u00a0<a href=\"https:\/\/www.superestagios.com.br\/index\/\" target=\"_blank\" rel=\"noopener noreferrer\">site da empresa<\/a>.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><em>(Fonte: G1\/Imagem: Reprodu\u00e7\u00e3o)<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Empresa Super Est\u00e1gios tamb\u00e9m oferece 50 vagas de est\u00e1gio na cidade, em diversas \u00e1reas de atua\u00e7\u00e3o.<\/p>\n","protected":false},"author":13,"featured_media":31381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2834,2828,5038,1],"tags":[5386,309,110],"class_list":["post-31373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-educacao","category-emprego","category-noticias","tag-ciee-jundiai","tag-estagio","tag-vagas"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/31373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=31373"}],"version-history":[{"count":1,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/31373\/revisions"}],"predecessor-version":[{"id":31375,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/31373\/revisions\/31375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/31381"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=31373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=31373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=31373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}