{"id":6927,"date":"2018-03-01T10:57:41","date_gmt":"2018-03-01T13:57:41","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=6927"},"modified":"2018-03-01T11:05:03","modified_gmt":"2018-03-01T14:05:03","slug":"educacao-prazo-para-inscricao-no-fies-e-prorrogado-para-sexta-feira-2","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2018\/03\/01\/educacao-prazo-para-inscricao-no-fies-e-prorrogado-para-sexta-feira-2\/","title":{"rendered":"Educa\u00e7\u00e3o: prazo para inscri\u00e7\u00e3o no Fies \u00e9 prorrogado para sexta-feira (2)"},"content":{"rendered":"<div id=\"attachment_6928\" style=\"width: 410px\" class=\"wp-caption alignright\"><a href=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/img_497.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6928\" class=\"wp-image-6928\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/img_497-300x168.jpg\" alt=\"\" width=\"400\" height=\"224\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/img_497-300x168.jpg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/img_497.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-6928\" class=\"wp-caption-text\">Para esta edi\u00e7\u00e3o, ser\u00e3o ofertadas 155 mil vagas<\/p><\/div>\n<p>O Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) decidiu prorrogar o per\u00edodo de inscri\u00e7\u00f5es para o Fundo de Financiamento Estudantil (Fies) referente ao primeiro semestre de 2018. Agora, o prazo termina na pr\u00f3xima sexta-feira (2).<\/p>\n<p>Segundo o MEC, a decis\u00e3o foi tomada para n\u00e3o prejudicar os candidatos e institui\u00e7\u00f5es, j\u00e1 que cerca de 400 mil inscri\u00e7\u00f5es ainda se encontram em fase de preenchimento no Sistema de Sele\u00e7\u00e3o do Fies. At\u00e9 as 17h de hoje (28), o\u00a0<a href=\"http:\/\/fiesselecao.mec.gov.br\/\" target=\"_blank\" rel=\"noopener\">sistema<\/a>\u00a0havia registrado 387.488 inscri\u00e7\u00f5es conclu\u00eddas e 427.431 inscri\u00e7\u00f5es em andamento. O prazo para as inscri\u00e7\u00f5es terminaria hoje (28).<\/p>\n<p>Pode se inscrever no Fies o estudante que tiver m\u00e9dia de pelo menos 450 pontos no Exame Nacional do Ensino M\u00e9dio (Enem) e que n\u00e3o tenha tirado nota zero na reda\u00e7\u00e3o. Outra exig\u00eancia \u00e9 se encaixar dentro dos limites de faixa de renda estabelecidos para o programa.<\/p>\n<p>Para esta edi\u00e7\u00e3o, ser\u00e3o ofertadas 155 mil vagas. No total, em 2018, o n\u00famero chegar\u00e1 a 310 mil vagas. Dessas, 100 mil ter\u00e3o juro zero para os estudantes que comprovarem renda per capita mensal familiar de at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos.<\/p>\n<p><em>(Fonte: Ag\u00eancia Brasil)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o foi tomada para n\u00e3o prejudicar os candidatos e institui\u00e7\u00f5es<\/p>\n","protected":false},"author":10,"featured_media":6928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1903,21,450,5,15],"class_list":["post-6927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-educacao","tag-fies","tag-jundiai","tag-tvtec"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=6927"}],"version-history":[{"count":1,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6927\/revisions"}],"predecessor-version":[{"id":6929,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6927\/revisions\/6929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=6927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=6927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=6927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}