{"id":6930,"date":"2018-03-01T11:01:04","date_gmt":"2018-03-01T14:01:04","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=6930"},"modified":"2018-03-01T11:02:29","modified_gmt":"2018-03-01T14:02:29","slug":"economia-receita-comeca-a-receber-declaracao-do-ir-da-pessoa-fisica-hoje-1o","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2018\/03\/01\/economia-receita-comeca-a-receber-declaracao-do-ir-da-pessoa-fisica-hoje-1o\/","title":{"rendered":"Economia: Receita come\u00e7a a receber Declara\u00e7\u00e3o do IR Pessoa F\u00edsica hoje (1)"},"content":{"rendered":"<div id=\"attachment_6931\" style=\"width: 410px\" class=\"wp-caption alignright\"><a href=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/23986861.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6931\" class=\"wp-image-6931\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/23986861-300x200.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/23986861-300x200.jpg 300w, https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2018\/03\/23986861.jpg 700w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-6931\" class=\"wp-caption-text\">A declara\u00e7\u00e3o poder\u00e1 ser preenchida por meio do programa baixado no computador ou do aplicativo Meu Imposto de Renda para tablets e celulares<\/p><\/div>\n<p>A Receita Federal recebe a partir das 8h de hoje (1\u00ba) as declara\u00e7\u00f5es do Imposto de Renda da Pessoa F\u00edsica (IRPF) 2018, ano-base 2017. O prazo para entrega vai at\u00e9 30 de abril. A declara\u00e7\u00e3o poder\u00e1 ser preenchida por meio do programa baixado no computador ou do aplicativo Meu Imposto de Renda para tablets e celulares.<\/p>\n<p>Este ano, \u00e9 obrigat\u00f3ria a apresenta\u00e7\u00e3o do Cadastro de Pessoa F\u00edsica (CPF) para dependentes a partir de 8 anos de idade, completados at\u00e9 o dia 31 de dezembro de 2017. Outra mudan\u00e7a \u00e9 a possibilidade de impress\u00e3o do Documento de Arrecada\u00e7\u00e3o de Receitas Federais (Darf) para pagamento de todas as cotas do imposto, inclusive as que est\u00e3o em atraso.<\/p>\n<p>Segundo a Receita, \u00e9 obrigado a declarar quem recebeu em 2017 rendimentos tribut\u00e1veis em valores superiores a R$ 28.559,70. No caso da atividade rural, deve declarar quem teve receita bruta acima de R$ 142.798,50. O Fisco espera receber, este ano, 28,8 milh\u00f5es de declara\u00e7\u00f5es do IRPF, 300 mil a mais do que em 2017 (28,5 milh\u00f5es).<\/p>\n<p>Tamb\u00e9m est\u00e3o obrigadas a declarar as pessoas f\u00edsicas residentes no Brasil que receberam rendimentos isentos, n\u00e3o tribut\u00e1veis ou tributados exclusivamente na fonte, cuja soma foi superior a R$ 40 mil; as que obtiveram, em qualquer m\u00eas, ganho de capital na aliena\u00e7\u00e3o de bens e direitos, sujeito \u00e0 incid\u00eancia do imposto ou que realizaram opera\u00e7\u00f5es em bolsas de valores; que pretendem compensar preju\u00edzos com a atividade rural; que tiveram, em 31 de dezembro de 2017, a posse ou a propriedade de bens e direitos, inclusive terra nua, de valor total superior a R$ 300 mil; que passaram \u00e0 condi\u00e7\u00e3o de residentes no Brasil em qualquer m\u00eas e assim se encontravam em 31 de dezembro; ou que optaram pela isen\u00e7\u00e3o do IR incidente sobre o ganho de capital com a venda de im\u00f3veis residenciais para a compra de outro im\u00f3vel no pa\u00eds, no prazo de 180 dias contados do contrato de venda.<\/p>\n<p><em>(Fonte: Ag\u00eancia Brasil)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prazo para entrega vai at\u00e9 30 de abril<\/p>\n","protected":false},"author":10,"featured_media":6932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,1],"tags":[1903,346,824,5,15],"class_list":["post-6930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-noticias","tag-brasil","tag-economia","tag-imposto-de-renda","tag-jundiai","tag-tvtec"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=6930"}],"version-history":[{"count":3,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6930\/revisions"}],"predecessor-version":[{"id":6935,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/6930\/revisions\/6935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/6932"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=6930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=6930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=6930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}