{"id":84386,"date":"2021-11-16T10:39:13","date_gmt":"2021-11-16T13:39:13","guid":{"rendered":"https:\/\/tvtecjundiai.com.br\/news\/?p=84386"},"modified":"2021-11-16T11:35:49","modified_gmt":"2021-11-16T14:35:49","slug":"grupo-de-danca-da-terceira-idade-faz-sucesso-em-jundiai","status":"publish","type":"post","link":"https:\/\/tvtecjundiai.com.br\/news\/2021\/11\/16\/grupo-de-danca-da-terceira-idade-faz-sucesso-em-jundiai\/","title":{"rendered":"Grupo de dan\u00e7a da terceira idade faz sucesso em Jundia\u00ed"},"content":{"rendered":"\n<p>Toda quinta-feira, \u00e0s 13h30, o Complexo Fepasa recebe o grupo de dan\u00e7a &#8216;Gera\u00e7\u00e3o +60&#8217;, composto por 11 casais que se encontram para dan\u00e7ar, conversar e se divertir. Nas aulas, o pessoal chega animado e energia \u00e9 o que n\u00e3o falta.<\/p>\n\n\n\n<p>A professora e core\u00f3grafa Mare Clini conta como o projeto surgiu. &#8220;O grupo surgiu em 2005, em uma brincadeira com m\u00fasica country na Associa\u00e7\u00e3o dos Aposentados e Pensionistas de Jundia\u00ed e Regi\u00e3o. A ideia deu certo, vieram mais alunos e eu fui mudando as coreografias. Tudo foi indo bem, a ponto de 11 casais se formarem para dan\u00e7ar. Depois de muitas apresenta\u00e7\u00f5es nos bailes da Associa\u00e7\u00e3o, come\u00e7amos a receber convites para fazer apresenta\u00e7\u00f5es. Acabamos virando uma fam\u00edlia&#8221;, explica. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/tvtecjundiai.com.br\/news\/wp-content\/uploads\/sites\/2\/2021\/11\/80293560_721317721723671_2272500520964849664_n.jpg\" alt=\"\" class=\"wp-image-84893\" \/><\/figure><\/div>\n\n\n\n<p>No grupo, p\u00e9 de valsa \u00e9 o que n\u00e3o falta. Seu Ren\u00ea e Seu Adirson, por exemplo, t\u00eam 82 anos e s\u00e3o muito conhecidos por seus passos de dan\u00e7a. J\u00e1 Darcy e Ot\u00e1vio Lazarini est\u00e3o juntos h\u00e1 46 anos e participam das aulas em busca de divers\u00e3o. &#8220;\u00c9 bom para a sa\u00fade e a mente, em especial. Nesse encontro a gente brinca, dan\u00e7a, conversa e se diverte. A dan\u00e7a \u00e9 tudo na vida da gente&#8221;, afirma Darcy.<\/p>\n\n\n\n<p>Aos poucos, todos s\u00e3o capazes de entrar no ritmo. &#8220;H\u00e1 uns 15 anos atr\u00e1s, me diziam que eu tinha que aprender a dan\u00e7ar. Como todo homem \u00e9 perna de pau, devagar eu fui entrando no ritmo e aprendendo. \u00c9 nesse momento que a mem\u00f3ria da gente \u00e9 ativada, nos d\u00e1 motiva\u00e7\u00e3o para que fa\u00e7amos cada vez melhor. Aqui s\u00e3o sempre aplausos atr\u00e1s de aplausos quando nos apresentamos&#8221;, diz Ot\u00e1vio.<\/p>\n\n\n\n<p>O &#8216;Grupo +60&#8217; tem coreografias de dan\u00e7a cigana, de super-her\u00f3i, forr\u00f3, ga\u00facha, colegial, anos 80, carnaval e muitas outras. Mas at\u00e9 todos estarem completamente vacinados, as apresenta\u00e7\u00f5es est\u00e3o voltando aos poucos. Mesmo assim, em um grupo t\u00e3o feliz, entre envelhecer em casa e envelhecer sorrindo, o ideal \u00e9 envelhecer dan\u00e7ando.<\/p>\n\n\n\n<p><em><strong>(Fonte: TVTEC\/Imagem: Arquivo Pessoal)<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grupo &#8216;Gera\u00e7\u00e3o +60&#8217; se re\u00fane toda quinta-feira no Complexo Fepasa.<\/p>\n","protected":false},"author":25,"featured_media":84893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,8356,1],"tags":[],"class_list":["post-84386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-jundiai","category-noticias"],"_links":{"self":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/84386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/comments?post=84386"}],"version-history":[{"count":3,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/84386\/revisions"}],"predecessor-version":[{"id":84902,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/posts\/84386\/revisions\/84902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media\/84893"}],"wp:attachment":[{"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/media?parent=84386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/categories?post=84386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtecjundiai.com.br\/news\/wp-json\/wp\/v2\/tags?post=84386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}